{"id":35819,"date":"2023-08-11T13:47:43","date_gmt":"2023-08-11T11:47:43","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=35819"},"modified":"2023-11-08T14:26:48","modified_gmt":"2023-11-08T13:26:48","slug":"betriebliche-suchtpraevention-aufbauseminar-teil-2-vom-6-11-aug-2023","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2023\/08\/11\/betriebliche-suchtpraevention-aufbauseminar-teil-2-vom-6-11-aug-2023\/","title":{"rendered":"Betriebliche Suchtpr\u00e4vention &#8211; Aufbauseminar (Teil 2) vom 6. &#8211; 11. Aug. 2023"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[204,234,80,25],"tags":[],"class_list":["post-35819","post","type-post","status-publish","format-standard","post-password-required","hentry","category-august-2023","category-betriebliche-suchtpraevention","category-fotoprotokoll","category-infomaterial"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:10:33","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/35819"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=35819"}],"version-history":[{"count":5,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/35819\/revisions"}],"predecessor-version":[{"id":36583,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/35819\/revisions\/36583"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=35819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=35819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=35819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}