{"id":34434,"date":"2023-03-31T11:27:13","date_gmt":"2023-03-31T09:27:13","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=34434"},"modified":"2023-04-14T11:21:20","modified_gmt":"2023-04-14T09:21:20","slug":"lx06323-qualifizierungsreihe-2022-des-gbr-fuer-neu-gewaehlte-br-mitglieder-an-den-standorten-der-daimler-truck-ag-reihe-b-modul-4-29-03-31-03-2023","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2023\/03\/31\/lx06323-qualifizierungsreihe-2022-des-gbr-fuer-neu-gewaehlte-br-mitglieder-an-den-standorten-der-daimler-truck-ag-reihe-b-modul-4-29-03-31-03-2023\/","title":{"rendered":"LX06323 Qualifizierungsreihe 2022 des GBR f\u00fcr neu gew\u00e4hlte BR-Mitglieder an den Standorten der Daimler Truck AG &#8211; Reihe B &#8211; Modul 4, 29.03. &#8211; 31. 03.2023"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196,213,199],"tags":[],"class_list":["post-34434","post","type-post","status-publish","format-standard","post-password-required","hentry","category-betriebsratsmitglieder","category-br-mitglieder-neu-firmen","category-maerz-2023"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:26:45","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/34434"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=34434"}],"version-history":[{"count":6,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/34434\/revisions"}],"predecessor-version":[{"id":34607,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/34434\/revisions\/34607"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=34434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=34434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=34434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}