{"id":33832,"date":"2023-02-03T07:00:24","date_gmt":"2023-02-03T06:00:24","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=33832"},"modified":"2023-03-06T10:18:31","modified_gmt":"2023-03-06T09:18:31","slug":"thp-ii-beschaeftigungssicherung-und-arbeitsgestaltung-fuer-menschen-mit-einer-schwer-behinderung-29-01-03-02-2023","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2023\/02\/03\/thp-ii-beschaeftigungssicherung-und-arbeitsgestaltung-fuer-menschen-mit-einer-schwer-behinderung-29-01-03-02-2023\/","title":{"rendered":"THP II &#8211; Besch\u00e4ftigungssicherung und Arbeitsgestaltung f\u00fcr Menschen mit einer (Schwer-)Behinderung, 29.01.-03.02.2023"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,33,80,176,171,25,224,60,167],"tags":[],"class_list":["post-33832","post","type-post","status-publish","format-standard","post-password-required","hentry","category-allgemein","category-beschaftigung-sichern","category-fotoprotokoll","category-gefaehrdungsbeurteilung","category-gesundheit-praevention-arbeitsschutz","category-infomaterial","category-sbv-praevention","category-sbv-teilhabepraxis-bem","category-seminarthemen"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:09:52","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/33832"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=33832"}],"version-history":[{"count":10,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/33832\/revisions"}],"predecessor-version":[{"id":34197,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/33832\/revisions\/34197"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=33832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=33832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=33832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}