{"id":31553,"date":"2022-05-18T10:43:46","date_gmt":"2022-05-18T08:43:46","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=31553"},"modified":"2022-05-20T10:44:34","modified_gmt":"2022-05-20T08:44:34","slug":"lx12022-rechtsgrundlagen-und-organisation-der-br-arbeit-powerpack-fuer-br-vorsitzende-und-stellvertreterinnen-teil-1-16-05-18-05-2022","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2022\/05\/18\/lx12022-rechtsgrundlagen-und-organisation-der-br-arbeit-powerpack-fuer-br-vorsitzende-und-stellvertreterinnen-teil-1-16-05-18-05-2022\/","title":{"rendered":"LX12022 Rechtsgrundlagen und Organisation der BR-Arbeit &#8211; Powerpack f\u00fcr BR-Vorsitzende und Stellvertreter*innen &#8211; Teil 1, 16.05. &#8211; 18.05.2022"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,187],"tags":[],"class_list":["post-31553","post","type-post","status-publish","format-standard","post-password-required","hentry","category-brv-und-stellvertreterinnen-powerpack","category-mai-2022"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:18:15","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31553"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=31553"}],"version-history":[{"count":4,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31553\/revisions"}],"predecessor-version":[{"id":31631,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31553\/revisions\/31631"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=31553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=31553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=31553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}