{"id":31156,"date":"2022-03-23T12:07:07","date_gmt":"2022-03-23T11:07:07","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=31156"},"modified":"2022-03-23T12:07:07","modified_gmt":"2022-03-23T11:07:07","slug":"lx01222-verhandlungen-beteiligungsorientiert-und-strategisch-fuehren-powerpack-fuer-br-vorsitzende-und-stellvertreterinnen-teil-4-21-03-23-03-2022","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2022\/03\/23\/lx01222-verhandlungen-beteiligungsorientiert-und-strategisch-fuehren-powerpack-fuer-br-vorsitzende-und-stellvertreterinnen-teil-4-21-03-23-03-2022\/","title":{"rendered":"LX01222 Verhandlungen beteiligungsorientiert und strategisch f\u00fchren &#8211; Powerpack f\u00fcr BR-Vorsitzende und Stellvertreter*innen &#8211; Teil 4, 21.03. &#8211; 23.03.2022"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,185],"tags":[],"class_list":["post-31156","post","type-post","status-publish","format-standard","post-password-required","hentry","category-brv-und-stellvertreterinnen-powerpack","category-maerz-2022"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:26:43","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31156"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=31156"}],"version-history":[{"count":2,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31156\/revisions"}],"predecessor-version":[{"id":31179,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/31156\/revisions\/31179"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=31156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=31156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=31156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}