{"id":30912,"date":"2022-02-11T09:58:21","date_gmt":"2022-02-11T08:58:21","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=30912"},"modified":"2022-03-09T15:46:11","modified_gmt":"2022-03-09T14:46:11","slug":"thp-iii-betriebliches-eingliederungsmanagement-arbeitsfaehigkeit-erhalten-und-sichern-06-11-02-2022","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2022\/02\/11\/thp-iii-betriebliches-eingliederungsmanagement-arbeitsfaehigkeit-erhalten-und-sichern-06-11-02-2022\/","title":{"rendered":"THP III Betriebliches Eingliederungsmanagement &#8211; Arbeitsf\u00e4higkeit erhalten und sichern, 06.-11.02.2022"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,181,80,176,171,25,60,167],"tags":[],"class_list":["post-30912","post","type-post","status-publish","format-standard","post-password-required","hentry","category-allgemein","category-datenschutz","category-fotoprotokoll","category-gefaehrdungsbeurteilung","category-gesundheit-praevention-arbeitsschutz","category-infomaterial","category-sbv-teilhabepraxis-bem","category-seminarthemen"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:22:25","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30912"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=30912"}],"version-history":[{"count":8,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30912\/revisions"}],"predecessor-version":[{"id":31116,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30912\/revisions\/31116"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=30912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=30912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=30912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}