{"id":30410,"date":"2021-11-26T11:50:51","date_gmt":"2021-11-26T10:50:51","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=30410"},"modified":"2021-11-26T12:13:37","modified_gmt":"2021-11-26T11:13:37","slug":"o71621047rb2-arbeitnehmer-innen-in-betrieb-wirtschaft-und-gesellschaft-i-21-26-11-2021","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2021\/11\/26\/o71621047rb2-arbeitnehmer-innen-in-betrieb-wirtschaft-und-gesellschaft-i-21-26-11-2021\/","title":{"rendered":"O71621047RB2 Arbeitnehmer\/innen in Betrieb, Wirtschaft und Gesellschaft I       21.\u201326.11.2021"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174,80,25,165],"tags":[],"class_list":["post-30410","post","type-post","status-publish","format-standard","post-password-required","hentry","category-an-betrieb-wirtschaft-gesellschaft","category-fotoprotokoll","category-infomaterial","category-november-2021"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:22:28","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30410"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=30410"}],"version-history":[{"count":8,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30410\/revisions"}],"predecessor-version":[{"id":30435,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/30410\/revisions\/30435"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=30410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=30410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=30410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}