{"id":28767,"date":"2021-02-12T07:00:37","date_gmt":"2021-02-12T06:00:37","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=28767"},"modified":"2021-02-26T18:20:15","modified_gmt":"2021-02-26T17:20:15","slug":"oa00621-thp-ii-beschaeftigungssicherung-und-arbeitsgestaltung-fuer-menschen-mit-einer-schwer-behinderung-07-12-02-2021","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2021\/02\/12\/oa00621-thp-ii-beschaeftigungssicherung-und-arbeitsgestaltung-fuer-menschen-mit-einer-schwer-behinderung-07-12-02-2021\/","title":{"rendered":"OA00621 THP II &#8211; Besch\u00e4ftigungssicherung und Arbeitsgestaltung f\u00fcr Menschen mit einer (Schwer-)Behinderung, 07.-12.02.2021"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,80,25,60,167],"tags":[],"class_list":["post-28767","post","type-post","status-publish","format-standard","post-password-required","hentry","category-allgemein","category-fotoprotokoll","category-infomaterial","category-sbv-teilhabepraxis-bem","category-seminarthemen"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:11:09","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28767"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=28767"}],"version-history":[{"count":7,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28767\/revisions"}],"predecessor-version":[{"id":28852,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28767\/revisions\/28852"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=28767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=28767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=28767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}