{"id":28470,"date":"2020-11-11T11:11:42","date_gmt":"2020-11-11T10:11:42","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=28470"},"modified":"2020-11-11T12:55:37","modified_gmt":"2020-11-11T11:55:37","slug":"ox34620-qualifizierungsreihe-2018-2020-des-gesamtbetriebsrats-fuer-neu-gewaehlte-betriebsratsmitglieder-in-den-niederlassungen-der-daimler-ag-reihe-k-4-baustein-09-11-11-11-2020","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2020\/11\/11\/ox34620-qualifizierungsreihe-2018-2020-des-gesamtbetriebsrats-fuer-neu-gewaehlte-betriebsratsmitglieder-in-den-niederlassungen-der-daimler-ag-reihe-k-4-baustein-09-11-11-11-2020\/","title":{"rendered":"OX34620 Qualifizierungsreihe 2018-2020 des Gesamtbetriebsrats f\u00fcr neu gew\u00e4hlte Betriebsratsmitglieder in den Niederlassungen der Daimler AG &#8211; Reihe K &#8211; 4. Baustein 09.11. &#8211; 11.11.2020"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,80,140],"tags":[],"class_list":["post-28470","post","type-post","status-publish","format-standard","post-password-required","hentry","category-brv-und-stellvertreterinnen-powerpack","category-fotoprotokoll","category-november-2019"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:26:29","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28470"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=28470"}],"version-history":[{"count":9,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28470\/revisions"}],"predecessor-version":[{"id":28570,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28470\/revisions\/28570"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=28470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=28470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=28470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}