{"id":28343,"date":"2020-10-23T07:00:00","date_gmt":"2020-10-23T05:00:00","guid":{"rendered":"https:\/\/seminare-lohr-bad-orb.de\/sft\/?p=28343"},"modified":"2020-11-17T08:10:59","modified_gmt":"2020-11-17T07:10:59","slug":"thp-iii-betriebliches-eingliederungsmanagement-bem-beschaeftigung-sichern-und-gesundheit-foerdern-18-23-10-2020","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2020\/10\/23\/thp-iii-betriebliches-eingliederungsmanagement-bem-beschaeftigung-sichern-und-gesundheit-foerdern-18-23-10-2020\/","title":{"rendered":"THP III &#8211; Betriebliches Eingliederungsmanagement (BEM): Besch\u00e4ftigung sichern und Gesundheit f\u00f6rdern, 18.-23.10.2020"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,80,25,60],"tags":[],"class_list":["post-28343","post","type-post","status-publish","format-standard","post-password-required","hentry","category-allgemein","category-fotoprotokoll","category-infomaterial","category-sbv-teilhabepraxis-bem"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:59:37","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28343"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=28343"}],"version-history":[{"count":13,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28343\/revisions"}],"predecessor-version":[{"id":28589,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/28343\/revisions\/28589"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=28343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=28343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=28343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}