{"id":19971,"date":"2018-09-14T12:54:54","date_gmt":"2018-09-14T10:54:54","guid":{"rendered":"http:\/\/seminare-lohr-bad-orb.de\/sft\/?p=19971"},"modified":"2018-09-27T13:38:28","modified_gmt":"2018-09-27T11:38:28","slug":"thp-3-betriebliches-eingliederungsmanagement-bem-v-9-14-sept-2018","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2018\/09\/14\/thp-3-betriebliches-eingliederungsmanagement-bem-v-9-14-sept-2018\/","title":{"rendered":"THP 3 &#8211; Betriebliches Eingliederungsmanagement (BEM) v. 9.-14.Sept. 2018"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,25,60,125],"tags":[],"class_list":["post-19971","post","type-post","status-publish","format-standard","post-password-required","hentry","category-fotoprotokoll","category-infomaterial","category-sbv-teilhabepraxis-bem","category-september-2018"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 10:02:51","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/19971"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=19971"}],"version-history":[{"count":6,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/19971\/revisions"}],"predecessor-version":[{"id":19981,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/19971\/revisions\/19981"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=19971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=19971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=19971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}