{"id":18779,"date":"2018-06-29T15:06:23","date_gmt":"2018-06-29T13:06:23","guid":{"rendered":"http:\/\/seminare-lohr-bad-orb.de\/sft\/?p=18779"},"modified":"2018-07-06T10:06:22","modified_gmt":"2018-07-06T08:06:22","slug":"ox22618-einfuehrung-br-arbeit-speziell-fuer-betriebsraete-aus-gesco-tochterunternehmen-24-06-29-06-2018","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2018\/06\/29\/ox22618-einfuehrung-br-arbeit-speziell-fuer-betriebsraete-aus-gesco-tochterunternehmen-24-06-29-06-2018\/","title":{"rendered":"OX22618 Einf\u00fchrung BR-Arbeit   speziell f\u00fcr Betriebsr\u00e4te aus Gesco-Tochterunternehmen      24.06.-29.06.2018"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,120],"tags":[],"class_list":["post-18779","post","type-post","status-publish","format-standard","post-password-required","hentry","category-fotoprotokoll","category-juni-2018"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:25:52","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/18779"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=18779"}],"version-history":[{"count":4,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/18779\/revisions"}],"predecessor-version":[{"id":18919,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/18779\/revisions\/18919"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=18779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=18779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=18779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}