{"id":16655,"date":"2017-11-10T08:50:46","date_gmt":"2017-11-10T07:50:46","guid":{"rendered":"http:\/\/seminare-lohr-bad-orb.de\/sft\/?p=16655"},"modified":"2017-12-06T15:52:17","modified_gmt":"2017-12-06T14:52:17","slug":"betriebliche-suchtpraevention-und-suchthilfe-1-vom-5-10-nov-2017","status":"publish","type":"post","link":"https:\/\/seminare-lohr-bad-orb.de\/sft\/2017\/11\/10\/betriebliche-suchtpraevention-und-suchthilfe-1-vom-5-10-nov-2017\/","title":{"rendered":"Betriebliche Suchtpr\u00e4vention und Suchthilfe 1 vom 5. &#8211; 10. Nov. 2017"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16655","post","type-post","status-publish","format-standard","post-password-required","hentry","category-allgemein"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:09:57","action":"Draft","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/16655"}],"collection":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/comments?post=16655"}],"version-history":[{"count":7,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/16655\/revisions"}],"predecessor-version":[{"id":17014,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/posts\/16655\/revisions\/17014"}],"wp:attachment":[{"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/media?parent=16655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/categories?post=16655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seminare-lohr-bad-orb.de\/sft\/wp-json\/wp\/v2\/tags?post=16655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}